{"id":355,"date":"2017-05-09T08:28:54","date_gmt":"2017-05-09T08:28:54","guid":{"rendered":"http:\/\/conditorei-museum.de\/?page_id=355"},"modified":"2020-11-27T08:00:29","modified_gmt":"2020-11-27T08:00:29","slug":"museum-mit-cafe","status":"publish","type":"page","link":"https:\/\/conditorei-museum.de\/index.php\/museum-mit-cafe\/","title":{"rendered":"Museum mit Caf\u00e9"},"content":{"rendered":"<div id=\"pl-355\"  class=\"panel-layout\" ><div id=\"pg-355-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-355-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-355-0-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"0\" ><div class=\"panel-widget-style panel-widget-style-for-355-0-0-0\" ><div class=\"so-widget-sow-editor so-widget-sow-editor-base\"><h3 class=\"widget-title\">Das Caf\u00e9<\/h3>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<p>Im ersten Obergeschoss erwartet dem Besucher ein elegantes, vollklimatisiertes Caf\u00e9 im Wiener Stil mit ca. 60 Sitzpl\u00e4tzen. Das gediegene Kirschholz - Interieur harmoniert ausgezeichnet mit den historischen Raum-Elementen aus der Zeit der Renaissance und des Barock, und schafft eine Atmosph\u00e4re zum Wohlf\u00fchlen.<\/p>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div><div id=\"pg-355-1\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-355-1-0\"  class=\"panel-grid-cell\" ><div id=\"panel-355-1-0-0\" class=\"so-panel widget widget_sow-image panel-first-child panel-last-child\" data-index=\"1\" ><div class=\"so-widget-sow-image so-widget-sow-image-default-d6014b76747a\">\n\n<div class=\"sow-image-container\">\n\t<img src=\"https:\/\/conditorei-museum.de\/wp-content\/uploads\/2018\/01\/cafe-bild-2.jpg\" width=\"1920\" height=\"1280\" srcset=\"https:\/\/conditorei-museum.de\/wp-content\/uploads\/2018\/01\/cafe-bild-2.jpg 1920w, https:\/\/conditorei-museum.de\/wp-content\/uploads\/2018\/01\/cafe-bild-2-300x200.jpg 300w, https:\/\/conditorei-museum.de\/wp-content\/uploads\/2018\/01\/cafe-bild-2-768x512.jpg 768w, https:\/\/conditorei-museum.de\/wp-content\/uploads\/2018\/01\/cafe-bild-2-1024x683.jpg 1024w, https:\/\/conditorei-museum.de\/wp-content\/uploads\/2018\/01\/cafe-bild-2-272x182.jpg 272w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" title=\"Foto: Gunter Kittel (Kitzingen)\" alt=\"\" \t\tclass=\"so-widget-image\"\/>\n<\/div>\n\n\t<h3 class=\"widget-title\">Foto: Gunter Kittel (Kitzingen)<\/h3><\/div><\/div><\/div><div id=\"pgc-355-1-1\"  class=\"panel-grid-cell\" ><div id=\"panel-355-1-1-0\" class=\"so-panel widget widget_sow-image panel-first-child panel-last-child\" data-index=\"2\" ><div class=\"so-widget-sow-image so-widget-sow-image-default-d6014b76747a\">\n\n<div class=\"sow-image-container\">\n\t<img src=\"https:\/\/conditorei-museum.de\/wp-content\/uploads\/2018\/01\/cafe-bild.jpg\" width=\"1920\" height=\"1280\" srcset=\"https:\/\/conditorei-museum.de\/wp-content\/uploads\/2018\/01\/cafe-bild.jpg 1920w, https:\/\/conditorei-museum.de\/wp-content\/uploads\/2018\/01\/cafe-bild-300x200.jpg 300w, https:\/\/conditorei-museum.de\/wp-content\/uploads\/2018\/01\/cafe-bild-768x512.jpg 768w, https:\/\/conditorei-museum.de\/wp-content\/uploads\/2018\/01\/cafe-bild-1024x683.jpg 1024w, https:\/\/conditorei-museum.de\/wp-content\/uploads\/2018\/01\/cafe-bild-272x182.jpg 272w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" title=\"Foto: Gunter Kittel (Kitzingen)\" alt=\"\" \t\tclass=\"so-widget-image\"\/>\n<\/div>\n\n\t<h3 class=\"widget-title\">Foto: Gunter Kittel (Kitzingen)<\/h3><\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Im ersten Obergeschoss erwartet dem Besucher ein elegantes, vollklimatisiertes Caf\u00e9 im Wiener Stil mit ca. 60 Sitzpl\u00e4tzen. Das gediegene Kirschholz &#8211; Interieur harmoniert ausgezeichnet mit den historischen Raum-Elementen aus der Zeit der Renaissance und des Barock, und schafft eine Atmosph\u00e4re zum Wohlf\u00fchlen.<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/template-full-width.php","meta":[],"_links":{"self":[{"href":"https:\/\/conditorei-museum.de\/index.php\/wp-json\/wp\/v2\/pages\/355"}],"collection":[{"href":"https:\/\/conditorei-museum.de\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/conditorei-museum.de\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/conditorei-museum.de\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/conditorei-museum.de\/index.php\/wp-json\/wp\/v2\/comments?post=355"}],"version-history":[{"count":15,"href":"https:\/\/conditorei-museum.de\/index.php\/wp-json\/wp\/v2\/pages\/355\/revisions"}],"predecessor-version":[{"id":967,"href":"https:\/\/conditorei-museum.de\/index.php\/wp-json\/wp\/v2\/pages\/355\/revisions\/967"}],"wp:attachment":[{"href":"https:\/\/conditorei-museum.de\/index.php\/wp-json\/wp\/v2\/media?parent=355"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}